{"id":14424,"date":"2021-09-02T14:10:23","date_gmt":"2021-09-02T12:10:23","guid":{"rendered":"\/es-es\/blogs\/running\/?p=14424"},"modified":"2024-06-11T13:44:03","modified_gmt":"2024-06-11T11:44:03","slug":"ejercicios-para-fortalecer-las-rodillas","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/ejercicios-para-fortalecer-las-rodillas\/","title":{"rendered":"\u00a14 Ejercicios para fortalecer las rodillas!"},"content":{"rendered":"<p>Te proponemos 4 sencillos ejercicios para fortalecer las rodillas: para que nunca tengas que decir eso de \u201cYo no puedo correr porque mis rodillas no lo aguantan\u201d&#8230;<\/p>\n<p><!--more--><\/p>\n<p>\u201cLa gente que corre termin\u00e1is con las rodillas destrozadas\u201d. \u201cEl running es el peor deporte para las articulaciones\u201d-<\/p>\n<p>Llevas oyendo este tipo de frases desde que te calzaste tus primeras zapatillas, pero \u00bfqu\u00e9 hay de cierto en todo ello? \u00bfPodemos proteger nuestras preciadas articulaciones para seguir practicando nuestro deporte favorito durante muchos a\u00f1os?<\/p>\n<p>\u00a1Claro que s\u00ed! Por eso esta semana venimos con una serie de ejercicios para fortalecer las rodillas, que te ayudaran a protegerlas y cuidarlas.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"14433\" data-permalink=\"\/es-es\/blogs\/running\/ejercicios-para-fortalecer-las-rodillas\/running_ejercicios_rodillas_1\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;--&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;1&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"running_ejercicios_rodillas_1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1.jpg\" class=\"alignnone wp-image-14433 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1.jpg\" alt=\"Ejercicios para fortalecer las rodillas\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_1-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El running conlleva miles y miles de impactos que son absorbidos por las diferentes articulaciones que entran en juego en este deporte, principalmente las de la cadera, rodilla y tobillo.<\/p>\n<p><strong>La combinaci\u00f3n de un buen trabajo de fuerza con uno propioceptivo y equilibrio es la mejor manera de prevenir molestias y lesiones, adem\u00e1s de asegurarse una buena salud a medio-largo plazo<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>4 SENCILLOS EJERCICIOS PARA FORTALECER LAS RODILLAS<\/strong><\/h3>\n<p>Si quieres seguir corriendo con 99 a\u00f1os, presta atenci\u00f3n a estos sencillos y efectivos ejercicios que ayudar\u00e1n a proteger y reforzar tus rodillas:<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>1. SENTADILLA ISOM\u00c9TRICA, el primero de los ejercicios para fortalecer las rodillas<\/strong><\/h2>\n<p>Todo un b\u00e1sico cuando empiezas a trabajar la fuerza o vuelves de una lesi\u00f3n. Sencillo, sin riesgos, un gran protector y aliado de nuestras estructuras musculares, tendinosas y ligamentosas.<\/p>\n<p>Apoya la espalda contra una pared, muro o \u00e1rbol y adopta la posici\u00f3n de sentado con los pies separados a la altura de los hombros aguantando 30 segundos. Recupera un minuto y repite hasta 4 veces con sus correspondientes descansos.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\" https:\/\/www.youtube.com\/embed\/k9Zh5LCpyPE\" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>2. SUBIDA AL BANCO MONOPODAL<\/strong><\/h2>\n<p>Este nos parece un ejercicio estrella para el running: fuerza, coordinaci\u00f3n, equilibrio, ritmo\u2026 Multiarticular, no sobrecarga las rodillas y mejora la movilidad del tren inferior\u2026.\u00bfte parece poco?<\/p>\n<p>Sube al banco con una pierna, exti\u00e9ndela y eleva la libre acerc\u00e1ndola al pecho. En esta ocasi\u00f3n no vamos alternando de pierna sino que realizamos hasta 12 repeticiones con la primera antes de cambiar a la otra.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\" https:\/\/www.youtube.com\/embed\/7yl3Kqjc1pc \" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>3. LUNGES (TIJERAS) FRONTALES AVANZANDO<\/strong><\/h2>\n<p>Esta variante de los lunges es muy interesante de cara a preservar la buena salud de nuestras rodillas porque m\u00e1s all\u00e1 del trabajo de fuerza que exige, nos reta a mantener el equilibrio en cada zancada con lo que reforzamos tendones y ligamentos.<\/p>\n<p>Avanza dando zancadas largas con el cuerpo derecho y bajando hasta casi rozar el suelo con la rodilla de la pierna que queda atr\u00e1s. Repite entre 8 y 12 veces con cada pierna y hasta 4 rondas. No te olvides de activar el core, ver\u00e1s qu\u00e9 diferencia.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\" https:\/\/www.youtube.com\/embed\/EK0Trlz7cO4 \" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>4. SKIPPING BAJO + APOYO A UNA PIERNA<\/strong><\/h2>\n<p>Puede resultarte divertido y retador en cuanto empieces a controlarlo. Ten cuidado al principio y vete progresando.<\/p>\n<p>Realiza un skipping bajo en el sitio sin elevar mucho las rodillas y da un peque\u00f1o salto con una pierna para caer sobre la otra manteniendo el equilibrio. Vete cambiando de pierna hasta llegar a 8-10 veces con cada una.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\" https:\/\/www.youtube.com\/embed\/qVibuQJbu5Y \" width=\"100%\" height=\"500\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Te recomendaos otros posts sobre entrenamiento y ejercicios que puedes encontrar en nuestro blog:<\/p>\n<ul>\n<li class=\"entry-title\"><strong><a href=\"\/es-es\/blogs\/running\/entrenamiento-y-descanso-en-el-running\/\" target=\"_blank\" rel=\"bookmark noopener\">ENTRENAMIENTO Y DESCANSO EN EL RUNNING: \u00bfC\u00d3MO LO HAGO?<\/a><\/strong><\/li>\n<li class=\"entry-title\"><strong><a href=\"\/es-es\/blogs\/running\/ejercicios-mejorar-la-estabilidad-de-la-pisada\/\" target=\"_blank\" rel=\"bookmark noopener\">\u00a14 EJERCICIOS PARA MEJORAR LA ESTABILIDAD DE LA PISADA!<\/a><\/strong><\/li>\n<li class=\"entry-title\"><strong><a href=\"\/es-es\/blogs\/running\/los-6-mejores-ejercicios-para-corredores-principiantes\/\" target=\"_blank\" rel=\"bookmark noopener\">LOS 6 MEJORES EJERCICIOS PARA CORREDORES PRINCIPIANTES<\/a><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te proponemos 4 sencillos ejercicios para fortalecer las rodillas: para que nunca tengas que decir eso de \u201cYo no puedo correr porque mis rodillas no lo aguantan\u201d&#8230; [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/ejercicios-para-fortalecer-las-rodillas\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":14434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"3","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":{"0":"post-14424","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entrenamiento"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2021\/09\/running_ejercicios_rodillas_portada.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-3KE","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/14424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=14424"}],"version-history":[{"count":18,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/14424\/revisions"}],"predecessor-version":[{"id":21491,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/14424\/revisions\/21491"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/14434"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=14424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=14424"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=14424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}