{"id":17297,"date":"2022-11-03T17:30:01","date_gmt":"2022-11-03T16:30:01","guid":{"rendered":"\/es-es\/blogs\/running\/?p=17297"},"modified":"2025-01-22T15:57:44","modified_gmt":"2025-01-22T14:57:44","slug":"nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/","title":{"rendered":"NNormal Tomir: la zapatilla de trail m\u00e1s polivalente de Camper"},"content":{"rendered":"<p>Camper nos presenta NNormal Tomir, un modelo de zapatilla con mayor abanico de posibilidades que su hermana mayor la Kjerag. \u00a1Conozc\u00e1mosla a fondo!<br \/>\n<!--more--><\/p>\n<p>La <a href=\"https:\/\/www.forumsport.com\/es-es\/nnormal-zapatillas-trail-hombre-tomir-20-n2ztr02-005-1000945764-p\" target=\"_blank\" rel=\"noopener\"><strong>NNormal Tomir<\/strong><\/a> debe su nombre a una monta\u00f1a de la tramuntana mallorquina perteneciente al municipio de Escorca, que tiene una altitud de 1.103 metros. Camper ha querido trasladar toda la energ\u00eda que se respira en su cima a su zapatilla m\u00e1s vers\u00e1til.<\/p>\n<p><strong>Este modelo est\u00e1 enfocado a corredores de cualquier peso que no tengan tanta experiencia en en el mundo del trail<\/strong> <strong>y que quieran embarcarse en aventuras de media-larga distancia a ritmos tranquilos<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17305\" data-permalink=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/g0015323\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"G0015323\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323.jpg\" class=\"alignnone wp-image-17305 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323.jpg\" alt=\"NNormal Tomir\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0015323-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Con <strong>260 gramos de peso en talla 8UK <\/strong>-297 gramos en talla 44 2\/3- y <strong>8 mil\u00edmetros de drop<\/strong> (31mm\/23mm), la casa mallorquina nos ofrece la posibilidad de adquirir las Tomir en 3 modelos diferentes: la Tomir \u201cnormal\u201d, la Tomir waterproof y las Tomir Boot waterproof. Estas dos \u00faltimas llevan incorporada una <strong>membrana impermeable<\/strong> llamada <strong>Sympatex<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Upper NNormal Tomir: resistencia sin l\u00edmites<\/strong><\/h2>\n<p>Al igual que en el modelo Kjerag, nos encontramos un upper sin grandes florituras, con <strong>un termosellado en puntera y una membrana Ripstop de Nylon que nos proporciona gran resistencia, mayor ligereza y mejor durabilidad al paso de los kil\u00f3metros<\/strong>.<\/p>\n<p>La transpirabilidad es muy buena, mejor que la del sistema Matryx -seg\u00fan nuestras sensaciones- usado en las Kjerag. Este modelo, a diferencia de los otros dos, <strong>no incorpora la membrana Sympatex, lo que hace que no sean impermeables.<\/strong><\/p>\n<p>Sin embargo, s\u00ed se favorece la pronta evacuaci\u00f3n del agua y la rapidez en el secado.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17310\" data-permalink=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/g0025389\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"G0025389\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389.jpg\" class=\"alignnone size-full wp-image-17310\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389.jpg\" alt=\"NNormal Tomir\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0025389-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Mediopie, la protecci\u00f3n justa para correr seguros<\/strong><\/h2>\n<p>Al pon\u00e9rnoslas por primera vez, se nota que <strong>est\u00e1n mas acolchadas que las Kjerag<\/strong>. De esta forma <strong>se consigue un poco mas de soporte, aunque la sensaci\u00f3n sigue siendo la de unas zapatillas m\u00e1s bien blandas, muy maleables.<\/strong><\/p>\n<p>Al igual que en el upper, <strong>los hilos de Nylon est\u00e1n presentes por todo el contorno<\/strong>, consiguiendo mayor ligereza y durabilidad.<\/p>\n<p>El lazado es asim\u00e9trico y, si en un primer momento no nos convenc\u00eda del todo, nos ha sacado de dudas saber que la raz\u00f3n de esto es que se evitan posibles puntos de presi\u00f3n y se mejora la sujeci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17308\" data-permalink=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/gopr5397\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GOPR5397\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397.jpg\" class=\"alignnone wp-image-17308 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397.jpg\" alt=\"NNormal Tomir\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/GOPR5397-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Todo el conjunto de las <a href=\"https:\/\/www.forumsport.com\/es-es\/nnormal-zapatillas-trail-hombre-tomir-20-n2ztr02-005-1000945764-p\" target=\"_blank\" rel=\"noopener\"><strong>Nnormal Tomir<\/strong><\/a> se nos ha amoldado perfectamente al pie, gracias en parte al correcto atado de los cordones -ojo que con lluvia si no se hace hincapi\u00e9 en esto puede que se os suelten-.<\/p>\n<p><strong>La plantilla de 3 mil\u00edmetros de grosor<\/strong> va pegada a la parte baja, manteni\u00e9ndose en su sitio en todo momento.<\/p>\n<p><strong>La leng\u00fceta es fina<\/strong>, minimalista dir\u00eda yo, <strong>unida por ambos laterales al chasis<\/strong> para evitar que pueda moverse.<\/p>\n<p>En todas las salidas realizadas no hemos tenido ning\u00fan dolor debido a desplazamientos de esta ni por aplicar excesiva tensi\u00f3n a los cordones. El tal\u00f3n va bien reforzado para mantenerlo en su lugar seg\u00fan pasen las horas.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17306\" data-permalink=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/g0085560\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"G0085560\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560.jpg\" class=\"alignnone size-full wp-image-17306\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560.jpg\" alt=\"NNormal Tomir\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0085560-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dos detalles a tener en cuenta<\/strong>:<\/p>\n<ul>\n<li>El<strong> tallaje es algo mayor de lo normal<\/strong><\/li>\n<li>Si os decid\u00eds por el modelo mas clarito, <strong>la limpieza despu\u00e9s de jornadas de barro y polvo ser\u00e1n mas complicada de lo normal<\/strong> ya que la suciedad se mete entre el entrelazado de los hilos de nylon.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>Mediasuela NNormal Tomir: pensada para todo tipo de corredores<\/strong><\/h2>\n<p>Uno de los detalles que nos llama la atenci\u00f3n es que <strong>va cosida <\/strong>-tambi\u00e9n pegada en parte- al chasis, detalle que ya hab\u00edamos olvidado en zapatillas de trail.<\/p>\n<p>La casa mallorquina explica que, adem\u00e1s de alargar la vida de la zapatilla, <strong>es una manera de, en un futuro, poder hacer un intercambio o reciclado menos laborioso<\/strong> que si fueran pegadas.<\/p>\n<p>En cuanto al compuesto principal, en las NNormal Tomir se apuesta por una <strong>Eva Midsole <\/strong>de baja densidad que har\u00e1 que tengamos bajo nuestros pies unas zapatillas menos reactivas que las Kjerag pero con <strong>mayor confort, mayor amortiguaci\u00f3n y menor peso<\/strong>.<\/p>\n<p>Todo esto unido a que <strong>la entresuela va sobredimensionada en la parte trasera<\/strong> -mayor base de apoyo y en consecuencia mayor estabilidad a la hora de pisar- hace que sea un modelo perfecto para corredores menos experimentados.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17307\" data-permalink=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/img_5120\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_5120\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120.jpg\" class=\"alignnone wp-image-17307 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120.jpg\" alt=\"NNormal Tomir\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/IMG_5120-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Y es que, cuando est\u00e1s empezando tiendes a talonar m\u00e1s por falta de t\u00e9cnica o acumulaci\u00f3n de cansancio.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Suela: m\u00e1s taco para m\u00e1s superficies<\/strong><\/h2>\n<p>Estamos hablando de <strong>tacos de 5,5 mil\u00edmetros<\/strong> de largura, con lo que <strong>el agarre en superficies mojadas o embarradas es magnifico<\/strong>, sobre todo gracias al compuesto de la suela &#8211;<strong>Vibram Megagrip, <\/strong>toda una garant\u00eda-.<\/p>\n<p>La tecnolog\u00eda <strong>Litebase <\/strong>consigue su objetivo, que es aligerar el peso global de la <a href=\"https:\/\/www.forumsport.com\/es-es\/nnormal-zapatillas-trail-hombre-tomir-20-n2ztr02-005-1000945764-p\" target=\"_blank\" rel=\"noopener\"><strong>NNormal Tomir<\/strong><\/a> sin sacrificar la comodidad a la hora de correr por zonas escarpadas.<\/p>\n<p>Al igual que la mediasuela, <strong>la suela es m\u00e1s ancha, por lo que la estabilidad y la amortiguaci\u00f3n ser\u00e1n mayores<\/strong>.<\/p>\n<p>El agarre, quitando piedras mojadas con restos de verd\u00edn es muy bueno y la sensaci\u00f3n de tracci\u00f3n en zonas grasas, espectacular.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17309\" data-permalink=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/g0075522\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"G0075522\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522.jpg\" class=\"alignnone wp-image-17309 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522.jpg\" alt=\"NNormal Tomir\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0075522-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Conclusiones Nnormal Tomir: ideales para correr muy c\u00f3modos a ritmos medios<br \/>\n<\/strong><\/h2>\n<p>Aunque no es una zapatilla tan voladora y reactiva como su hermana, con el lanzamiento de este modelo <strong>Camper consigue llegar a mayor n\u00famero de corredores, sin importar su fisionom\u00eda, la distancia que quieran correr o el terreno pisen<\/strong>.<\/p>\n<p>Est\u00e1n muy bien amortiguadas, sin excesivos acolchados ni protecciones que las convertir\u00edan en zapatillas m\u00e1s pesadas.<\/p>\n<p>Aunque hay que afinar con el tallaje, gracias a la sobredimensi\u00f3n de la suela y mediasuela y a sus generosos perfiles, tenemos unas zapatillas ideales para hacer kil\u00f3metros por todo tipo de terrenos sin sacrificar nuestra comodidad. Sobre todo si somos runners de ritmos medios.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-17297-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887407-00-P-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17600&quot;,&quot;title&quot;:&quot;medias-1000887407-00-P-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887407-01-X-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17601&quot;,&quot;title&quot;:&quot;medias-1000887407-01-X-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887407-02-S-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17602&quot;,&quot;title&quot;:&quot;medias-1000887407-02-S-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887407-03-X-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17603&quot;,&quot;title&quot;:&quot;medias-1000887407-03-X-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887408-00-P-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17604&quot;,&quot;title&quot;:&quot;medias-1000887408-00-P-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887408-01-X-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17605&quot;,&quot;title&quot;:&quot;medias-1000887408-01-X-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887408-02-S-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17606&quot;,&quot;title&quot;:&quot;medias-1000887408-02-S-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/medias-1000887408-03-X-X-20221014164418.jpg&quot;,&quot;id&quot;:&quot;17607&quot;,&quot;title&quot;:&quot;medias-1000887408-03-X-X-20221014164418&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>COMODIDAD:<\/strong> 4\/5.<\/li>\n<li><strong>AGARRE: <\/strong>4\/5.<\/li>\n<li><strong>ESTABILIDAD:<\/strong> 5\/5.<\/li>\n<li><strong>LIGEREZA:<\/strong> 5\/5.<\/li>\n<li><strong>AMORTIGUACI\u00d3N:<\/strong> 4\/5.<\/li>\n<li><strong>DURABILIDAD:<\/strong> 5\/5.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Camper nos presenta NNormal Tomir, un modelo de zapatilla con mayor abanico de posibilidades que su hermana mayor la Kjerag. \u00a1Conozc\u00e1mosla a fondo! [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/nnormal-tomir-la-zapatilla-de-trail-mas-polivalente-de-camper\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":607,"featured_media":17303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"2","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-17297","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-material-de-running"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2022\/10\/G0055478.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-4uZ","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/17297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/607"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=17297"}],"version-history":[{"count":6,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/17297\/revisions"}],"predecessor-version":[{"id":23519,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/17297\/revisions\/23519"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/17303"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=17297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=17297"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=17297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}