{"id":1814,"date":"2016-04-19T17:02:39","date_gmt":"2016-04-19T15:02:39","guid":{"rendered":"\/es-es\/blogs\/running\/?p=1814"},"modified":"2025-01-22T16:14:01","modified_gmt":"2025-01-22T15:14:01","slug":"pasion-por-correr-18-de-abril-2016","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/pasion-por-correr-18-de-abril-2016\/","title":{"rendered":"Pasi\u00f3n por correr 18 de Abril 2016"},"content":{"rendered":"<p>Podcast con el programa del Lunes 18 de Abril. En <a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/pasionporcorrer?source=feed_text&amp;story_id=1540683529566646\" data-ft=\"{&quot;tn&quot;:&quot;*N&quot;,&quot;type&quot;:104}\"><span class=\"_58cl\">\u202a#\u200e<\/span><span class=\"_58cm\">pasionporcorrer\u202c<\/span><\/a> en Vinilo FM www.vinilo.fm o en el 96.7 de la FM (en la zona de Uribe Kosta, Bilbao y Margen Izqda.) de 21:00 a 22:00, con Dani Oneka Boada, Jesus Beamonte, y nuestros expertos Elena Jorr\u00edn, Dietista-Nutricionista (Nutrici\u00f3n) y David Herrero (Osteopat\u00eda y Fisioterapia).<!--more--><\/p>\n<p><span class=\"text_exposed_show\">Y como invitados,<\/span> entrevistamos al Preparador F\u00edsico, especialista en Alto Rendimiento&#8230;y facilitador de sue\u00f1os,&nbsp;<a href=\"https:\/\/www.facebook.com\/octavio.perezcalatayud\/?fref=ts\" target=\"_blank\" rel=\"noopener\">Octavio Perez<\/a>.<\/p>\n<p>Musicalmente, esta vez nos acompa\u00f1ar\u00e1n los Guns N&#8217; Roses.<span id=\"more-1769\"><\/span><\/p>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-1814-1\" preload=\"metadata\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.ivoox.com\/pasion-correr-18-04-2016_md_11209929_wp_1.mp3?_=1\" \/><a href=\"http:\/\/www.ivoox.com\/pasion-correr-18-04-2016_md_11209929_wp_1.mp3\">http:\/\/www.ivoox.com\/pasion-correr-18-04-2016_md_11209929_wp_1.mp3<\/a><\/audio>\n<p><a title=\"Pasion por correr 18\/04\/2016\" href=\"http:\/\/www.ivoox.com\/pasion-correr-18-04-2016-audios-mp3_rf_11209929_1.html\">Ir a descargar<\/a><\/p>\n<p>Si quieres contactar con el programa o aportar cualquier sugerencia dir\u00edgete por favor a <a href=\"mailto:pasionporcorrer@vinilofm.es\">pasionporcorrer@vinilofm.es<\/a> o en Facebook <a href=\"https:\/\/www.facebook.com\/pasionporcorrerKM\/?fref=ts\" target=\"_blank\" rel=\"noopener\">Pasi\u00f3nporcorrer<\/a>.<\/p>\n<p>Ya sabes please, Comenta y COMPARTE, sobre todo COMPARTE que nos ayudas a llegar m\u00e1s lejos.<br \/>\nGracias, os esperamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podcast con el programa del Lunes 18 de Abril. En \u202a#\u200epasionporcorrer\u202c en Vinilo FM www.vinilo.fm o en el 96.7 de la FM (en la zona de Uribe Kosta, Bilbao y Margen Izqda.) de 21:00 a 22:00, con Dani Oneka Boada, Jesus Beamonte, y nuestros expertos Elena Jorr\u00edn, Dietista-Nutricionista (Nutrici\u00f3n) y David Herrero (Osteopat\u00eda y Fisioterapia). [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/pasion-por-correr-18-de-abril-2016\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":1817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[54],"tags":[129,106,105,140,93,138,142,107,141],"class_list":{"0":"post-1814","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-podcasts","8":"tag-entrenamiento","9":"tag-fisioterapia","10":"tag-nutricion","11":"tag-pasion-por-correr","12":"tag-podcast","13":"tag-podcasts","14":"tag-suplementacion","15":"tag-tratamiento","16":"tag-vinilo-fm"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2016\/04\/13051693_1540683406233325_3640271700566397881_n_blog-running-forum-sport.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-tg","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/1814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=1814"}],"version-history":[{"count":11,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/1814\/revisions"}],"predecessor-version":[{"id":23539,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/1814\/revisions\/23539"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/1817"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=1814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=1814"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=1814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}