{"id":21981,"date":"2024-08-06T09:41:46","date_gmt":"2024-08-06T07:41:46","guid":{"rendered":"\/es-es\/blogs\/running\/?p=21981"},"modified":"2024-08-06T09:41:46","modified_gmt":"2024-08-06T07:41:46","slug":"hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/","title":{"rendered":"HOKA SPEEDGOAT 6: M\u00c1S LIGERA, M\u00c1S R\u00c1PIDA Y M\u00c1S DIN\u00c1MICA"},"content":{"rendered":"<p>La marca originaria de los Alpes franceses nos vuelve a sorprender con la nueva versi\u00f3n de uno de sus modelos m\u00e1s demandados hasta la fecha: la Hoka Speedgoat 6. Reci\u00e9n salida del Flylab -centro de innovaci\u00f3n de Hoka-, esta nueva versi\u00f3n es la m\u00e1s ligera hasta la fecha, con <strong>apenas 278 gramos en una talla 44<\/strong>. \u00a1Pero veamos cu\u00e1les son sus <strong>novedades<\/strong>!<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21993\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprogopr3779-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROGOPR3779.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722404469&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;114&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROGOPR3779.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprogopr3779.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-1024x768.jpeg\" class=\"alignnone size-full wp-image-21993\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Upper <a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-hombre-speedgoat6-1147791-1001005020-p\" target=\"_blank\" rel=\"noopener\">Hoka Speedgoat 6<\/a>: m\u00e1s ce\u00f1ido y minimalista<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>El upper ha sido una de las zonas responsables de conseguir la zapatilla m\u00e1s ligera hasta la fecha: siguiendo la din\u00e1mica de otras marcas, <strong>Hoka ha optado por el uso de una malla de tejido textil \u201cminimalista\u201d y muy transpirable<\/strong>, logrando que nuestro pie no sude en exceso en d\u00edas calurosos.<\/p>\n<p>Como consecuencia, el paso del agua ser\u00e1 inmediato pero la evacuaci\u00f3n de esta y el secado tambi\u00e9n.<\/p>\n<p>Al ser la <strong>malla<\/strong> tan <strong>fina<\/strong> podr\u00eda dar la sensaci\u00f3n de que su durabilidad se ve comprometida, pero en todos los kil\u00f3metros y salidas que hemos realizado con ellas puestas y despu\u00e9s de unos cuantos roces y enganchones no hemos visto se\u00f1ales de posibles roturas o zonas deshilachadas.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21990\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprogopr3804-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROGOPR3804.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722412168&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;394&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROGOPR3804.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprogopr3804.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-1024x768.jpeg\" class=\"alignnone size-full wp-image-21990\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00003-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Toda la puntera est\u00e1 reforzada por termosellados<\/strong> con puntos en forma de salpicones carentes de material que \u2013creemos- tienen la funci\u00f3n de reducir el peso del conjunto.<\/p>\n<p>En estas Hoka Speedgoat 6, <strong>la banda de termosellado acaba algo m\u00e1s atr\u00e1s de la l\u00ednea de flexi\u00f3n de los dedos con lo que toda esta parte de la zapatilla estar\u00e1 m\u00e1s protegida ante roturas. <\/strong><\/p>\n<p>En cuanto a <strong>la anchura del upper, decir que va bastante ce\u00f1ido,<\/strong> lo que en un primer momento podr\u00eda parecer contradictorio para realizar tiradas largas. Pues bien, aunque esa sea la primera sensaci\u00f3n, al ser una malla tan minimalista y con una zona central m\u00e1s el\u00e1stica, en pocos kil\u00f3metros se amolda perfectamente a nuestro pie.<\/p>\n<p>El uso de calcetines m\u00e1s o menos gruesos tambi\u00e9n influir\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22002\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/proyecto-nuevo-2024-08-05t111507-023\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"proyecto nuevo 2024 08 05t111507.023\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023.jpg\" class=\"alignnone size-full wp-image-22002\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111507.023-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-hombre-speedgoat6-1147791-1001005020-p\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5181\" data-permalink=\"\/es-es\/blogs\/running\/test-asics-nimbus-19-lima-segundos-suma-proteccion-y-ligereza\/nimbus19_test\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test.jpg\" data-orig-size=\"1980,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"nimbus19_test\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-300x109.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-1024x372.jpg\" class=\"aligncenter wp-image-5181 size-full\" src=\"https:\/\/blogs.forumsport.com\/es-es\/blogs\/montana\/wp-content\/uploads\/sites\/3\/2019\/10\/BOT\u00d3N-ver-producto.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"105\" height=\"30\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Mediopie: sencillo pero efectivo<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Es una <strong>continuaci\u00f3n de la malla usada en el upper<\/strong>, con una muy <strong>buena adaptabilidad<\/strong> a la morfolog\u00eda de nuestro pie.<\/p>\n<p>Si colocamos las <strong><a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-mujer-speedgoat6-1147811-1001005021-p\" target=\"_blank\" rel=\"noopener\">Hoka Speedgoat 6<\/a><\/strong> a contraluz podemos apreciar tanto lo fina que es la malla como el conjunto de tiras que har\u00e1n de refuerzo para mantener la estabilidad y estructura en la zona.<\/p>\n<p><strong>La leng\u00fceta es bastante minimalista<\/strong>, unida al resto del mediopie a ambos lados por su cara interna para\u2026<\/p>\n<ul>\n<li>Mantenerse en su lugar con el paso de los kil\u00f3metros.<\/li>\n<li>Dar mayor estabilidad.<\/li>\n<\/ul>\n<p>En su parte m\u00e1s alta posee un <strong>acolchado extra<\/strong> para que el atado de los cordones no nos moleste. Estos \u00faltimos son planos, con 6 ojales y una banda central por donde pasan para mantenerse en su lugar.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21999\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprog0023677-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROG0023677.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722403949&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;212&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROG0023677.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprog0023677.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-1024x768.jpeg\" class=\"alignnone size-full wp-image-21999\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00012-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Toda la zona del collar de las Hoka Speedgoat 6 va muy bien acolchada, subiendo un poco en el \u00e1rea del tend\u00f3n de Aquiles para darnos mayor protecci\u00f3n<\/strong>.<\/p>\n<p>El tirador incluido en la parte trasera ser\u00e1 un buen aliado a la hora de calz\u00e1rnoslas.<\/p>\n<p>En esta sexta versi\u00f3n, <strong>Hoka ha incorporado un contrafuerte en el tal\u00f3n que nos da mucha estabilidad y protecci\u00f3n.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22003\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/proyecto-nuevo-2024-08-05t111800-420\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"proyecto nuevo 2024 08 05t111800.420\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420.jpg\" class=\"alignnone size-full wp-image-22003\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t111800.420-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-hombre-speedgoat6-1147791-1001005020-p\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5181\" data-permalink=\"\/es-es\/blogs\/running\/test-asics-nimbus-19-lima-segundos-suma-proteccion-y-ligereza\/nimbus19_test\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test.jpg\" data-orig-size=\"1980,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"nimbus19_test\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-300x109.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-1024x372.jpg\" class=\"aligncenter wp-image-5181 size-full\" src=\"https:\/\/blogs.forumsport.com\/es-es\/blogs\/montana\/wp-content\/uploads\/sites\/3\/2019\/10\/BOT\u00d3N-ver-producto.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"105\" height=\"30\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Esta es una caracter\u00edstica primordial a la hora de movernos por lugares inestables o al realizar tiradas largas, en las que nuestra pisada comienza a perder efectividad. El tal\u00f3n se mantendr\u00e1 en su lugar y de esta forma <strong>evitaremos posibles lesiones a corto y largo plazo<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Mediasuela <a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-mujer-speedgoat6-1147811-1001005021-p\" target=\"_blank\" rel=\"noopener\">Hoka Speedgoat 6<\/a>: ligera y muy bien amortiguada<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Aqu\u00ed reside gran parte del \u00e9xito de las Hoka. Por un lado tenemos el <strong>Active Foot Frame<\/strong>, una especie de chasis de <strong>sujeci\u00f3n interna<\/strong> que se crea a trav\u00e9s de la elevaci\u00f3n de las paredes de la entresuela. El pie queda encajado, sujet\u00e1ndose muy bien y ganando <strong>estabilidad<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21993\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprogopr3779-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROGOPR3779.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722404469&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;114&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROGOPR3779.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprogopr3779.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-1024x768.jpeg\" class=\"alignnone size-full wp-image-21993\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00006-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Y por otro lado tenemos el <strong>compuesto CMEVA<\/strong>, <strong>algo m\u00e1s ligero que en modelos anteriores y que funcionar\u00e1 como un amortiguador de alto rendimiento<\/strong>. De esta manera se consigue una zapatilla de <strong>5 mil\u00edmetros -35mm\/40mm- de Drop<\/strong> bien amortiguada, con un poco m\u00e1s de altura -incorpora m\u00e1s material- y con un dinamismo muy bueno.<\/p>\n<p>Aunque el uso de pintura en la parte superior de la mediasuela pudiera dar la sensaci\u00f3n de que esta se compone de varios materiales, nada m\u00e1s lejos de la realidad. Se trata de una t\u00e9cnica para dar cierta <strong>protecci\u00f3n<\/strong> y as\u00ed <strong>evitar o retrasar el desgaste de la zona<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21995\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprogopr3766-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROGOPR3766.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722404309&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;355&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROGOPR3766.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprogopr3766.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-1024x768.jpeg\" class=\"alignnone size-full wp-image-21995\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00008-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Suela: m\u00e1ximo agarre en todo tipo de terrenos<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Como no pod\u00eda ser de otra forma si hablamos de la Goat, los tacos de las Hoka Speedgoat 6 est\u00e1n inspirados en las <strong>pezu\u00f1as de una cabra<\/strong>.<\/p>\n<p><strong>Tienen una largura de 5 mil\u00edmetros, con una nueva orientaci\u00f3n y la tecnolog\u00eda Traction Lug<\/strong> -mini puntos o relieves en los propios tacos que dan mayor agarre y seguridad-.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22001\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprog0013619-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROG0013619.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722403927&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;327&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROG0013619.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprog0013619.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-1024x768.jpeg\" class=\"alignnone size-full wp-image-22001\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00014-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La suela <strong>est\u00e1 compuesta por el Vibram Megagrip<\/strong>, material del que solo podemos decir cosas positivas ya que su <strong>agarre<\/strong> en todo tipo de superficies es <strong>espectacular<\/strong>.<\/p>\n<p>Respecto al modelo anterior y como novedad tenemos 3 tacos que se han incorporado en la parte delantera externa. Su funci\u00f3n es darnos <strong>mayor agarre y seguridad<\/strong> en terrenos m\u00e1s complicados.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22005\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/proyecto-nuevo-2024-08-05t112204-123\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"proyecto nuevo 2024 08 05t112204.123\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123.jpg\" class=\"alignnone size-full wp-image-22005\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"800\" height=\"600\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123.jpg 800w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t112204.123-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-hombre-speedgoat6-1147791-1001005020-p\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5181\" data-permalink=\"\/es-es\/blogs\/running\/test-asics-nimbus-19-lima-segundos-suma-proteccion-y-ligereza\/nimbus19_test\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test.jpg\" data-orig-size=\"1980,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"nimbus19_test\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-300x109.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-1024x372.jpg\" class=\"aligncenter wp-image-5181 size-full\" src=\"https:\/\/blogs.forumsport.com\/es-es\/blogs\/montana\/wp-content\/uploads\/sites\/3\/2019\/10\/BOT\u00d3N-ver-producto.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"105\" height=\"30\"><\/a><\/p>\n<h2>&nbsp;<\/h2>\n<h2><strong>Conclusiones <a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-hombre-speedgoat6-1147791-1001005020-p\" target=\"_blank\" rel=\"noopener\">Hoka Speedgoat 6<\/a>: una devoradora de senderos que hace que correr parezca f\u00e1cil<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><strong>Una de las cosas que m\u00e1s nos ha sorprendido ha sido su peso ya que, aunque a primera vista parece una zapatilla voluminosa, este es relativamente bajo. <\/strong><\/p>\n<p>Seg\u00fan te la pones se nota que el upper va bastante ce\u00f1ido, lo cual te hace pensar en si la zona de los dedos se ver\u00e1 afectada con el paso de los kil\u00f3metros.<\/p>\n<p>En nuestro caso y siendo de esos a los que les gusta un upper holgado s\u00ed que hemos echado en falta un poco m\u00e1s de anchura, aunque nos ha sorprendido que <strong>la malla se amolda muy bien al contorno del pie<\/strong> con el paso de los kil\u00f3metros.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21994\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprog0053743-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-scaled.jpeg\" data-orig-size=\"2560,1704\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROG0053743.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722404229&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;180&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROG0053743.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprog0053743.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-300x200.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-1024x682.jpeg\" class=\"alignnone size-full wp-image-21994\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1704\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-300x200.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-1024x682.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-768x511.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-1536x1022.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00007-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>No sabemos si el tejido usado en la zona central del upper -debajo de los cordones- tendr\u00e1 algo que ver.<\/p>\n<p>En cuanto a la transpirabilidad, no hemos notado exceso de calor, ni en d\u00edas calurosos ni tampoco en las tiradas en las que hemos llevado calcetines m\u00e1s gordos.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21997\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprog0043726-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROG0043726.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722404061&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;233&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROG0043726.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprog0043726.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-1024x768.jpeg\" class=\"alignnone size-full wp-image-21997\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00010-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>La malla es muy resistente a rozaduras y la incorporaci\u00f3n de los termosellados en la zona delantera hace que el conjunto de la zapatilla tenga mayor durabilidad<\/strong>.<\/p>\n<p>Aunque no hemos tenido ning\u00fan problema, <strong>s\u00ed que creemos que la leng\u00fceta tendr\u00eda que se un poco m\u00e1s larga,<\/strong> ya que el atado de los cordones queda un poco justo sobre ella. Tanto el grosor como el plus de estabilidad que ofrece al ir sujeta por ambos lados son buenos.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21992\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprog0073795-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROG0073795.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722404528&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0023419203747073&quot;,&quot;title&quot;:&quot;DCIM100GOPROG0073795.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprog0073795.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-1024x768.jpeg\" class=\"alignnone size-full wp-image-21992\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00005-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Otra de las caracter\u00edsticas que nos ha sorprendido para bien y que s\u00ed que se nota es la tecnolog\u00eda Active Foot Frame.<\/strong> El pie va s\u00faper encajado y estable en terrenos t\u00e9cnicos, con lo que la sensaci\u00f3n de seguridad es brutal.<\/p>\n<p>Esto hace que podamos exprimirnos con mayor seguridad y a ritmos mayores.<\/p>\n<p>Aunque no seamos capaces de apreciar que <strong>el compuesto CMEVA usado en este modelo es m\u00e1s ligero que en ediciones anteriores<\/strong>, s\u00ed que nos ha gustado la sensaci\u00f3n de llevar una zapatilla bien amortiguada y con cierta reactividad.<\/p>\n<p>No soy de esos corredores a los que les entusiasma correr con zapatillas voluminosas, pero <strong>con estas Speedgoat me he sentido muy c\u00f3modo y seguro<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21989\" data-permalink=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/dcim100goprog0083823-jpg\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HERO9 Black&quot;,&quot;caption&quot;:&quot;DCIM100GOPROG0083823.JPG&quot;,&quot;created_timestamp&quot;:&quot;1722405265&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.0041666666666667&quot;,&quot;title&quot;:&quot;DCIM100GOPROG0083823.JPG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dcim100goprog0083823.jpg\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-300x225.jpeg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-1024x768.jpeg\" class=\"alignnone size-full wp-image-21989\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-scaled.jpeg\" alt=\"HOKA SPEEDGOAT 6\" width=\"2560\" height=\"1920\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-scaled.jpeg 2560w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-300x225.jpeg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-1024x768.jpeg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-768x576.jpeg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-1536x1152.jpeg 1536w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/image00001-2048x1536.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>En cuanto a la suela y su compuesto Vibram, decir que seg\u00fan te las pones, esa primera sensaci\u00f3n de pegarte al suelo es una pasada<\/strong>; se va perdiendo con el uso, pero no deja de ser algo que nos encanta.<\/p>\n<p>Tanto la orientaci\u00f3n del taqueado como su geometr\u00eda y el uso de la tecnolog\u00eda Traction Lug es un acierto de Hoka ya que agarran muy bien en todo tipo de terrenos y superficies. Y aunque su largura es de 5 mil\u00edmetros, en zonas blandas cumplen su fusi\u00f3n con creces.<\/p>\n<p>As\u00ed que ya sab\u00e9is, si est\u00e1is buscando una zapatilla relativamente <strong>ligera, con buena amortiguaci\u00f3n y un agarre espectacular<\/strong> sobre <strong>todo tipo de terrenos<\/strong> para exprimirlas durante horas, pasaros por Forum Sport y \u00a1haceros con vuestras cabras veloces antes de que se acaben!<\/p>\n<ul>\n<li><strong>Amortiguaci\u00f3n:<\/strong> 4\/5.<\/li>\n<li><strong>Agarre:<\/strong> 5\/5.<\/li>\n<li><strong>Ligereza:<\/strong> 4\/5.<\/li>\n<li><strong>Estabilidad:<\/strong> 5\/5.<\/li>\n<li><strong>Comodidad:<\/strong> 4\/5.<\/li>\n<li><strong>Durabilidad:<\/strong> 3\/5.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-21981-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/hoka-zapatillas-trail-mujer-speedgoat6-lateral-interior-1001005021-1000x1000-f.jpg&quot;,&quot;id&quot;:&quot;22007&quot;,&quot;title&quot;:&quot;hoka zapatillas trail mujer speedgoat6 lateral interior 1001005021 1000\\u0026#215;1000 f&quot;,&quot;alt&quot;:&quot;hoka zapatillas trail mujer speedgoat6 lateral interior 1001005021 1000x1000 f&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/hoka-zapatillas-trail-mujer-speedgoat6-puntera-1001005021-1000x1000-f.jpg&quot;,&quot;id&quot;:&quot;22008&quot;,&quot;title&quot;:&quot;hoka zapatillas trail mujer speedgoat6 puntera 1001005021 1000\\u0026#215;1000 f&quot;,&quot;alt&quot;:&quot;hoka zapatillas trail mujer speedgoat6 puntera 1001005021 1000x1000 f&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/hoka-zapatillas-trail-mujer-speedgoat6-vista-trasera-1001005021-1000x1000-f.jpg&quot;,&quot;id&quot;:&quot;22009&quot;,&quot;title&quot;:&quot;hoka zapatillas trail mujer speedgoat6 vista trasera 1001005021 1000\\u0026#215;1000 f&quot;,&quot;alt&quot;:&quot;hoka zapatillas trail mujer speedgoat6 vista trasera 1001005021 1000x1000 f&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/hoka-zapatillas-trail-mujer-speedgoat6-vista-superior-1001005021-1000x1000-f-1.jpg&quot;,&quot;id&quot;:&quot;22012&quot;,&quot;title&quot;:&quot;hoka zapatillas trail mujer speedgoat6 vista superior 1001005021 1000\\u0026#215;1000 f (1)&quot;,&quot;alt&quot;:&quot;HOKA SPEEDGOAT 6&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/hoka-zapatillas-trail-mujer-speedgoat6-05-1001005021-1000x1000-f.jpg&quot;,&quot;id&quot;:&quot;22010&quot;,&quot;title&quot;:&quot;hoka zapatillas trail mujer speedgoat6 05 1001005021 1000\\u0026#215;1000 f&quot;,&quot;alt&quot;:&quot;hoka zapatillas trail mujer speedgoat6 05 1001005021 1000x1000 f&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/08\\\/hoka-zapatillas-trail-mujer-speedgoat6-06-1001005021-1000x1000-f.jpg&quot;,&quot;id&quot;:&quot;22011&quot;,&quot;title&quot;:&quot;hoka zapatillas trail mujer speedgoat6 06 1001005021 1000\\u0026#215;1000 f&quot;,&quot;alt&quot;:&quot;hoka zapatillas trail mujer speedgoat6 06 1001005021 1000x1000 f&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p><a href=\"https:\/\/www.forumsport.com\/es-es\/hoka-zapatillas-trail-mujer-speedgoat6-1147811-1001005021-p\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5181\" data-permalink=\"\/es-es\/blogs\/running\/test-asics-nimbus-19-lima-segundos-suma-proteccion-y-ligereza\/nimbus19_test\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test.jpg\" data-orig-size=\"1980,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"nimbus19_test\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-300x109.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/03\/nimbus19_test-1024x372.jpg\" class=\"aligncenter wp-image-5181 size-full\" src=\"https:\/\/blogs.forumsport.com\/es-es\/blogs\/montana\/wp-content\/uploads\/sites\/3\/2019\/10\/BOT\u00d3N-ver-producto.jpg\" alt=\"HOKA SPEEDGOAT 6\" width=\"105\" height=\"30\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ahora s\u00f3lo tienes que salir a correr y disfrutar de estas zapatillas. Te ense\u00f1amos aqu\u00ed algunos ejercicios y consejos:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.forumsport.com\/es-es\/blogs\/running\/7-ejercicios-para-ganar-velocidad-corriendo\/\">7 EJERCICIOS PARA GANAR VELOCIDAD CORRIENDO<\/a><\/li>\n<li><a href=\"https:\/\/www.forumsport.com\/es-es\/blogs\/running\/guia-entrenamiento-runners-a-partir-cincuenta-anos-consejos\/\">GU\u00cdA DE ENTRENAMIENTO RUNNERS A PARTIR DE LOS 50: \u00a1SIGUE ESTOS CONSEJOS!<\/a><\/li>\n<li><a href=\"https:\/\/www.forumsport.com\/es-es\/blogs\/running\/como-evitar-un-golpe-de-calor-cuando-corres\/\">C\u00d3MO EVITAR UN GOLPE DE CALOR CUANDO CORRES EN VERANO<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La marca originaria de los Alpes franceses nos vuelve a sorprender con la nueva versi\u00f3n de uno de sus modelos m\u00e1s demandados hasta la fecha: la Hoka Speedgoat 6. Reci\u00e9n salida del Flylab -centro de innovaci\u00f3n de Hoka-, esta nueva versi\u00f3n es la m\u00e1s ligera hasta la fecha, con apenas 278 gramos en una talla [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/hoka-speedgoat-6-mas-ligera-mas-rapida-y-mas-dinamica\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":607,"featured_media":21988,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":{"0":"post-21981","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-material-de-running"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2024\/08\/proyecto-nuevo-2024-08-05t110629.582.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-5Ix","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/21981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/607"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=21981"}],"version-history":[{"count":7,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/21981\/revisions"}],"predecessor-version":[{"id":22016,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/21981\/revisions\/22016"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/21988"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=21981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=21981"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=21981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}