{"id":4135,"date":"2017-05-03T16:23:05","date_gmt":"2017-05-03T14:23:05","guid":{"rendered":"\/es-es\/blogs\/running\/?p=4135"},"modified":"2017-05-04T17:00:13","modified_gmt":"2017-05-04T15:00:13","slug":"test-saucony-freedom-iso-mejores-zapatillas-running","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/","title":{"rendered":"Test Saucony Freedom ISO: \u00bfLas mejores zapatillas de running del a\u00f1o?"},"content":{"rendered":"<p>Me hab\u00edan hablado maravillas de estas zapatillas de running (ajuste inmejorable, reactividad\u2026.) as\u00ed que estaba deseando sacarlas de su caja y comprobar qu\u00e9 sensaciones me iban a dar. En el&nbsp; momento de calz\u00e1rmelas no daba cr\u00e9dito: mejoraba todas las expectativas que hab\u00eda depositado en&nbsp; ellas, empezando por el dise\u00f1o y terminando por cada una de las tecnolog\u00edas de las nuevas <strong><a href=\"https:\/\/www.forumsport.com\/saucony-zapatilla-running-hombre-freedom-iso-s20355-3-422305\/\" target=\"_blank\">Saucony Freedom ISO<\/a><\/strong>: \u00bfSon las mejores zapatillas del a\u00f1o? Veamos&#8230;<\/p>\n<p><!--more--><\/p>\n<h2>UPPER<\/h2>\n<p>Un upper dise\u00f1ado con la <strong>malla engineered mesh, sin costuras, sin tejidos superpuestos, muy ligero y transpirable<\/strong>. Su desarrollo lo han basado en dos piezas:<\/p>\n<ul>\n<li>Una m\u00e1s interna -tipo calcet\u00edn- que proporciona suavidad y un gran ajuste al pie.<\/li>\n<li>Y otra exterior que, por medio unos cortes en forma de tirante sujetos a la media suela, &nbsp;aporta un refuerzo extra en el ajuste del pie (<strong>Tecnolog\u00eda isofit<\/strong>).<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4144\" data-permalink=\"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/saucony-freedom-iso-4\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-4.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"saucony freedom iso 4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-4-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-4.jpg\" class=\"aligncenter size-full wp-image-4144\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-4.jpg\" alt=\"\" height=\"480\" width=\"640\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-4.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-4-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4160\" data-permalink=\"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/saucony-freedom-iso-7\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-7.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"saucony-freedom-iso-7\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-7-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-7.jpg\" class=\"aligncenter size-full wp-image-4160\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-7.jpg\" alt=\"\" height=\"480\" width=\"640\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-7.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony-freedom-iso-7-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>MEDIA SUELA<\/h2>\n<p>En la media suela, la gran inc\u00f3gnita era el rendimiento que nos aportar\u00eda toda una pieza entera de <strong>Everun<\/strong>, la espuma caracter\u00edstica de la marca. Este material ofrece&nbsp;<strong>una amortiguaci\u00f3n m\u00e1s firme y reactiva<\/strong> y <strong>facilita la adaptaci\u00f3n a la zancada de cada corredor<\/strong>.<\/p>\n<p>La respuesta, mejor de lo esperado tambi\u00e9n: <strong>ligera, reactiva, flexible y con una amortiguaci\u00f3n de tacto muy agradable<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4146\" data-permalink=\"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/mediasuela-3\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/mediasuela.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mediasuela\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/mediasuela-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/mediasuela.jpg\" class=\"aligncenter size-full wp-image-4146\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/mediasuela.jpg\" alt=\"\" height=\"480\" width=\"640\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/mediasuela.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/mediasuela-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>SUELA<\/h2>\n<p>En la suela&nbsp;podemos encontrar un dise\u00f1o y juego de colores muy logrado. Fabricada&nbsp;en&nbsp;<strong>una sola pieza con goma de cristal<\/strong>, cuenta con&nbsp;la misma firmeza desde el tal\u00f3n hasta los dedos. En principio, la durabilidad est\u00e1 garantizada, aunque obviamente depender\u00e1 tambi\u00e9n del tipo de terreno en el que entrenemos. En&nbsp;mi caso, asfalto y&nbsp; con tiradas de ritmos diferentes, algunas series y fraccionados, la suela est\u00e1 como nueva.<\/p>\n<p>Los<strong>&nbsp;peque\u00f1os tacos, evoluci\u00f3n de Tri-flex de Saucony <\/strong>(con un tama\u00f1o m\u00e1s peque\u00f1o de lo habitual), nos aportan una <strong>buena tracci\u00f3n en terrenos de asfalto y tierra dura<\/strong>. En suelo seco el agarre es muy bueno, en cambio con suelo h\u00famedo tendremos que tener algo mas de precauci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4156\" data-permalink=\"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/saucony_suela\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_suela.jpg\" data-orig-size=\"640,550\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"saucony_suela\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_suela-300x258.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_suela.jpg\" class=\"aligncenter size-full wp-image-4156\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_suela.jpg\" alt=\"\" height=\"550\" width=\"640\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_suela.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_suela-300x258.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>CONCLUSI\u00d3N<\/h2>\n<p>El <strong>comportamiento de las Freedom Iso es espectacular<\/strong>. Zapatilla tipo mixta, con una <strong>amortiguaci\u00f3n brutal, reactiva, r\u00e1pida y con muy buena respuesta en rodajes largos a ritmos vivos<\/strong>.<\/p>\n<p>Orientada a <strong>entrenamiento-mixto<\/strong>, &nbsp;para&nbsp; <strong>runners de peso bajo \/ medio, o competici\u00f3n para runners de m\u00e1s peso<\/strong>. No podemos pasar por alto el <strong>drop 4<\/strong> que nos ofrece el modelo, <strong>ideal para runners que entren de mediopi\u00e9<\/strong>. Bien es cierto que tiene una pieza de material m\u00e1s resistente en la zona del tal\u00f3n para ofrecer mayor estabilidad en esta zona.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4220\" data-permalink=\"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/saucony_corregido_pant\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_corregido_pant.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"saucony_corregido_pant\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_corregido_pant-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_corregido_pant.jpg\" class=\"aligncenter size-full wp-image-4220\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_corregido_pant.jpg\" alt=\"\" height=\"480\" width=\"640\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_corregido_pant.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_corregido_pant-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>El <strong>ajuste<\/strong> que ofrece al pie es <strong>perfecto<\/strong>, aunque requiere una buena t\u00e9cnica de carrera. El <strong>tallaje de la zapatilla es ajustado<\/strong>, un poco corto, dato a tener en cuenta para los que us\u00e1is plantillas correctoras.<\/p>\n<p><strong>Mi consejo es utilizarla como segunda zapatilla, algo que nos active y nos ponga las pilas para correr fuerte, un estimulo positivo para buscar m\u00e1s rendimiento.<\/strong> En&nbsp;cuanto al&nbsp;material, Saucony siempre ofrece modelos buen\u00edsimos, pero con \u00e9ste han dado especialmente en la diana.<\/p>\n<p>Despu\u00e9s de haber testado esta zapatilla durante un mes,&nbsp; creo que la apuesta por este modelo no va a decepcionar. En la que es una de las apuestas de Saucony para esta primavera, la marca estadounidense ha hecho un gran trabajo: si no son las mejores zapatillas del a\u00f1o, es seguro que estar\u00e1n entre las mejores&#8230;<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">El pase de diapositivas requiere JavaScript.<\/p><div id=\"gallery-4135-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/saucony-freedom-iso-1.jpg&quot;,&quot;id&quot;:&quot;4141&quot;,&quot;title&quot;:&quot;saucony freedom iso 1&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/saucony-freedom-iso-2.jpg&quot;,&quot;id&quot;:&quot;4142&quot;,&quot;title&quot;:&quot;saucony freedom iso 2&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/saucony-freedom-iso-3.jpg&quot;,&quot;id&quot;:&quot;4143&quot;,&quot;title&quot;:&quot;saucony freedom iso 3&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/blogs.forumsport.com\\\/es-es\\\/blogs\\\/running\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/saucony-freedom-iso-4.jpg&quot;,&quot;id&quot;:&quot;4144&quot;,&quot;title&quot;:&quot;saucony freedom iso 4&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<p><strong>LIGEREZA <\/strong>&#8211;&nbsp; 8,5<br \/>\n<strong>AMORTIGUACI\u00d3N<\/strong> &#8211; 8<br \/>\n<strong>ESTABILIDAD<\/strong> &#8211; 7<br \/>\n<strong>AGARRE<\/strong> &#8211; 8<br \/>\n<strong>RESPUESTA<\/strong> &#8211; 9<\/p>\n<p><strong>SUPERFICIE<\/strong>: Asfalto.<br \/>\n<strong>DROP<\/strong>: 4<br \/>\n<strong>PISADA<\/strong> NEUTRA.<br \/>\n<strong>APOYO DE PIE<\/strong>:&nbsp; MEDIO, DELANTERO.<br \/>\n<strong>PESO<\/strong>: 255 GR.<br \/>\n<strong>USO<\/strong>:&nbsp;Entrenamientos r\u00e1pidos y competici\u00f3n.<br \/>\n<strong>TESTER<\/strong>: 56 KG con pisada neutra.<br \/>\n<strong>Ritmos en los que se ha testado<\/strong>:&nbsp;3,20-4,30.<\/p>\n<p><em>Por: Ritxar Fern\u00e1ndez, <strong>Tester y especialista runner en Forum Sport<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me hab\u00edan hablado maravillas de estas zapatillas de running (ajuste inmejorable, reactividad\u2026.) as\u00ed que estaba deseando sacarlas de su caja y comprobar qu\u00e9 sensaciones me iban a dar. En el&nbsp; momento de calz\u00e1rmelas no daba cr\u00e9dito: mejoraba todas las expectativas que hab\u00eda depositado en&nbsp; ellas, empezando por el dise\u00f1o y terminando por cada una de [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/test-saucony-freedom-iso-mejores-zapatillas-running\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":4155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[2],"tags":[75,199,392,393,394],"class_list":{"0":"post-4135","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-material-de-running","8":"tag-amortiguacion","9":"tag-saucony","10":"tag-saucony-freedom-iso","11":"tag-tecnologia-isofit","12":"tag-tri-flex"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/saucony_prueba_destacado1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-14H","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/4135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=4135"}],"version-history":[{"count":16,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/4135\/revisions"}],"predecessor-version":[{"id":4221,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/4135\/revisions\/4221"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/4155"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=4135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=4135"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=4135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}