{"id":4372,"date":"2017-05-31T01:00:11","date_gmt":"2017-05-30T23:00:11","guid":{"rendered":"\/es-es\/blogs\/running\/?p=4372"},"modified":"2020-03-20T13:36:09","modified_gmt":"2020-03-20T12:36:09","slug":"tres-desayunos-runners-para-este-verano","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/tres-desayunos-runners-para-este-verano\/","title":{"rendered":"Tres desayunos runners para cualquier \u00e9poca del a\u00f1o"},"content":{"rendered":"<p>\u00bfEres de los que piensa que los desayunos son aburridos? A pesar de que no es la comida m\u00e1s importante del d\u00eda -todas lo son-, si es una de las m\u00e1s descuidadas. Por eso, hoy nos volvemos a poner el delantal y nos metemos en la cocina para hacer recetas de desayuno diferentes: dulces, salados, ligeros, energ\u00e9ticos, fr\u00edos, calientes\u2026el mundo de los desayunos nunca fue tan variado y apetecible.<\/p>\n<p><!--more--><\/p>\n<p>Son recetas que valen para cualquier \u00e9poca del a\u00f1o: ahora que tendr\u00e1s algo m\u00e1s de tiempo, es momento de probar nuevos y nutritivos desayunos que te ayuden a mantenerte en forma.<\/p>\n<h2>TORTITAS DE AVENA<\/h2>\n<h3>Ingredientes:<\/h3>\n<ul>\n<li>50 gramos de copos de avena molidos<\/li>\n<li>25 gramos de salvado de avena<\/li>\n<li>1 huevo<\/li>\n<li>1 vaso de bebida vegetal (avena y coco por ejemplo, pero puedes usar el sabor que m\u00e1s te guste)<\/li>\n<li>1\/2 cucharadita de semillas de chia<\/li>\n<li>1 pizca de levadura<\/li>\n<li>1 pizca de vainilla en polvo.<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n:<\/h3>\n<p>Mezclamos todos los ingredientes, dejamos reposar la mezcla 30&#8242; y nos ponemos manos a la obra: &nbsp;cogemos una cucharadita de aceite de oliva virgen extra y, cuando est\u00e9 bien caliente, vertemos la masa en la sart\u00e9n. As\u00ed vamos haciendo las tortitas una a una: no necesitan mucho tiempo para hacerse: en unos minutos, vuelta y vuelta, \u00a1y estar\u00e1n listas!<\/p>\n<p>Las puedes acompa\u00f1ar de <strong>pl\u00e1tano<\/strong> (como en la foto), <strong>compota de manzana<\/strong>, <strong>canela<\/strong>, etc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4378\" data-permalink=\"\/es-es\/blogs\/running\/tres-desayunos-runners-para-este-verano\/drtortitas\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRTORTITAS.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DRTORTITAS\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRTORTITAS-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRTORTITAS.jpg\" class=\"aligncenter size-full wp-image-4378\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRTORTITAS.jpg\" alt=\"desayunos runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRTORTITAS.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRTORTITAS-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>GRANOLA CASERA Y MANZANA CON CREMA DE CACAHUETE, AVENA, FRUTOS SECOS Y PEPITAS DE CHOCOLATE<\/h2>\n<h3><strong>Granola: <\/strong><\/h3>\n<h3>Ingredientes:<\/h3>\n<p>En sustituci\u00f3n de los t\u00edpicos cereales de desayuno, la granola es muy sencilla de hacer y nos sirve para&nbsp; mezclar con yogur o leche.<\/p>\n<ul>\n<li>50 gr de copos de avena<\/li>\n<li>25 gramos de quinoa hinchada<\/li>\n<li>50 gramos de avellanas y almendras<\/li>\n<li>1 cucharada sopera de pipas de calabaza<\/li>\n<li>1 cucharada sopera de uvas pasas<\/li>\n<li>1 cucharada de miel<\/li>\n<li>1 cucharada de aceite de oliva<\/li>\n<li>1 cucharada de canela en polvo (opcional)<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n:<\/h3>\n<p>Precalentamos el horno, mezclamos&nbsp; los ingredientes (excepto la miel y el aceite) y los ponemos en una bandeja de horno. Horneamos a 150\u00ba durante 10&#8242;, sacamos del horno, removemos y a\u00f1adimos la miel y el aceite. &nbsp;Dejamos unos 10&#8242; m\u00e1s, enfriamos y lo guardamos en un frasco de cristal herm\u00e9tico.<\/p>\n<h3><strong>Manzana con crema de cacahuete<\/strong><\/h3>\n<p>Esta receta es <strong>muy r\u00e1pida y sencilla<\/strong>. Lavamos una <strong>manzana<\/strong> y la cortamos en rodajas. Las untamos con <strong>crema de cacahuete<\/strong> (si es comprada,&nbsp; aseguraros que es cacahuete 100%, sino la podemos hacer en casa moliendo los cacahuetes durante 15 minutos en un robot de cocina) y a\u00f1adimos <strong>avena en copos<\/strong>, <strong>almendras molidas<\/strong>, <strong>pasas<\/strong> y <strong>chocolate<\/strong> (m\u00ednimo con un 70% cacao).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4375\" data-permalink=\"\/es-es\/blogs\/running\/tres-desayunos-runners-para-este-verano\/drgranola-y-manzana\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRgranola-y-manzana.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DRgranola y manzana\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRgranola-y-manzana-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRgranola-y-manzana.jpg\" class=\"aligncenter size-full wp-image-4375\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRgranola-y-manzana.jpg\" alt=\"desayunos runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRgranola-y-manzana.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRgranola-y-manzana-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>PUDDING DE CHIA Y FRUTAS Y MUFFINS DE HUEVO<\/h2>\n<p>Para los amantes de los desayunos originales y diferentes.<\/p>\n<h3><strong>Pudding de chia<\/strong><\/h3>\n<h3>Ingredientes:<\/h3>\n<ul>\n<li>1 vaso de bebida vegetal (yo he usado leche de avena casera)<\/li>\n<li>2 cucharadas soperas de semillas de chia<\/li>\n<li>Pl\u00e1tano, fresas, kiwi, pasas y avellanas<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n:<\/h3>\n<p>Mezclamos la bebida vegetal y las semillas de chia y las dejamos reposar hasta que espesen y se forme una gelatina.<\/p>\n<p>Colocamos en un bol las capas de frutas, el pudding ya hecho gel, las avellanas y las pasas<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4376\" data-permalink=\"\/es-es\/blogs\/running\/tres-desayunos-runners-para-este-verano\/drpudding-de-chia\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRpudding-de-chia.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DRpudding de chia\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRpudding-de-chia-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRpudding-de-chia.jpg\" class=\"aligncenter size-full wp-image-4376\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRpudding-de-chia.jpg\" alt=\"desayunos runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRpudding-de-chia.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRpudding-de-chia-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h3><strong>Muffins de huevo<\/strong><\/h3>\n<p>Una alternativa para comer huevo en el desayuno.<\/p>\n<p>Hemos elaborado <strong>3 tipos de muffins<\/strong>:<\/p>\n<p>-De <strong>huevo<\/strong>, <strong>espinacas<\/strong> y <strong>queso fresco de cabra<\/strong>.<\/p>\n<p>-De <strong>huevo<\/strong>, <strong>tomate<\/strong> y <strong>queso fresco de cabra<\/strong>.<\/p>\n<p>-De <strong>huevo<\/strong> y <strong>pl\u00e1tano<\/strong>.<\/p>\n<h3>Preparaci\u00f3n:<\/h3>\n<p>Ponemos en un molde para hacer muffins los ingredientes elegidos, cubrimos con huevo batido y llevamos al horno 20 minutos a 180 grados. El resultado no puede estar m\u00e1s rico y m\u00e1s sorprendente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4374\" data-permalink=\"\/es-es\/blogs\/running\/tres-desayunos-runners-para-este-verano\/drchia-y-muffins\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRchia-y-muffins.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DRchia y muffins\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRchia-y-muffins-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRchia-y-muffins.jpg\" class=\"aligncenter size-full wp-image-4374\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRchia-y-muffins.jpg\" alt=\"desayunos runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRchia-y-muffins.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/DRchia-y-muffins-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>\u00a1Te toca a ti! \u00bfCon cu\u00e1l de estos desayunos te vas a atrever?<\/p>\n<p><em>Por&nbsp;<strong><a href=\"https:\/\/www.facebook.com\/Elena-Jorr%C3%ADn-Dietista-Nutricionista-588638977837653\/\" target=\"_blank\" rel=\"noopener\">Elena Jorr\u00edn<\/a><\/strong> (Dietista Nutricionista, especialista en nutrici\u00f3n deportiva y coach nutricional).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEres de los que piensa que los desayunos son aburridos? A pesar de que no es la comida m\u00e1s importante del d\u00eda -todas lo son-, si es una de las m\u00e1s descuidadas. Por eso, hoy nos volvemos a poner el delantal y nos metemos en la cocina para hacer recetas de desayuno diferentes: dulces, salados, [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/tres-desayunos-runners-para-este-verano\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":4379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[5],"tags":[292,411,293,414,413,412,410,415],"class_list":{"0":"post-4372","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nutricion-y-salud","8":"tag-chocolate","9":"tag-desayuno-runners","10":"tag-frutos-secos","11":"tag-granola-casera","12":"tag-muffin-de-huevo","13":"tag-pudding-de-chia","14":"tag-recetas-runners","15":"tag-tortitas-de-avena"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/05\/portada-DR.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-18w","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/4372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=4372"}],"version-history":[{"count":11,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/4372\/revisions"}],"predecessor-version":[{"id":11202,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/4372\/revisions\/11202"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/4379"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=4372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=4372"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=4372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}