{"id":5470,"date":"2017-12-04T08:00:02","date_gmt":"2017-12-04T07:00:02","guid":{"rendered":"\/es-es\/blogs\/running\/?p=5470"},"modified":"2017-12-12T17:55:55","modified_gmt":"2017-12-12T16:55:55","slug":"coaching-nutricional-moda-o-profesion","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/coaching-nutricional-moda-o-profesion\/","title":{"rendered":"Coaching Nutricional: \u00bfModa o profesi\u00f3n?"},"content":{"rendered":"<p>Hace ya unos a\u00f1os que el t\u00e9rmino <em><strong>coaching<\/strong><\/em> y <em><strong>coach<\/strong><\/em> nos resulta familiar, pero \u00bfsabes realmente qu\u00e9 es el <em>coaching<\/em>? \u00bfEs tan solo una moda? \u00bfPor qu\u00e9 genera tanta confusi\u00f3n?<\/p>\n<p>Como dietista nutricionista y especialista en <em>coaching<\/em> nutricional, es hora de explicaros desde mis conocimientos y experiencia esta nueva disciplina.<\/p>\n<p><!--more--><\/p>\n<p>El <strong><em>coaching<\/em> nutricional<\/strong> es un proceso de cambio y aprendizaje, donde el paciente (el runner en este caso) identifica el objetivo que quiere conseguir, vence los obst\u00e1culos y se convierte en el protagonista de sus logros, asumiendo su responsabilidad y aprendiendo a usar herramientas para conseguir sus objetivos.<\/p>\n<blockquote class=\"areago-addtoany-blockquote\"><div class=\"addtoany_shortcode\"><div class=\"a2a_kit a2a_kit_size_24 addtoany_list\" data-a2a-url=\"\/es-es\/blogs\/running\/coaching-nutricional-moda-o-profesion\/#quote-1\" data-a2a-title=\"\u201cEl informar y dar consejo por parte del profesional,&nbsp;ya no es suficiente para conseguir cambios&nbsp;de comportamiento a largo plazo\u201d.&nbsp;Organizaci\u00f3n Mundial de la Salud (2003)\"><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fblogs.forumsport.com%2Fes-es%2Fblogs%2Frunning%2Fcoaching-nutricional-moda-o-profesion%2F%23quote-1&amp;linkname=%E2%80%9CEl%20informar%20y%20dar%20consejo%20por%20parte%20del%20profesional%2C%26nbsp%3Bya%20no%20es%20suficiente%20para%20conseguir%20cambios%26nbsp%3Bde%20comportamiento%20a%20largo%20plazo%E2%80%9D.%26nbsp%3BOrganizaci%C3%B3n%20Mundial%20de%20la%20Salud%20%282003%29\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fblogs.forumsport.com%2Fes-es%2Fblogs%2Frunning%2Fcoaching-nutricional-moda-o-profesion%2F%23quote-1&amp;linkname=%E2%80%9CEl%20informar%20y%20dar%20consejo%20por%20parte%20del%20profesional%2C%26nbsp%3Bya%20no%20es%20suficiente%20para%20conseguir%20cambios%26nbsp%3Bde%20comportamiento%20a%20largo%20plazo%E2%80%9D.%26nbsp%3BOrganizaci%C3%B3n%20Mundial%20de%20la%20Salud%20%282003%29\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_linkedin\" href=\"https:\/\/www.addtoany.com\/add_to\/linkedin?linkurl=https%3A%2F%2Fblogs.forumsport.com%2Fes-es%2Fblogs%2Frunning%2Fcoaching-nutricional-moda-o-profesion%2F%23quote-1&amp;linkname=%E2%80%9CEl%20informar%20y%20dar%20consejo%20por%20parte%20del%20profesional%2C%26nbsp%3Bya%20no%20es%20suficiente%20para%20conseguir%20cambios%26nbsp%3Bde%20comportamiento%20a%20largo%20plazo%E2%80%9D.%26nbsp%3BOrganizaci%C3%B3n%20Mundial%20de%20la%20Salud%20%282003%29\" title=\"LinkedIn\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fblogs.forumsport.com%2Fes-es%2Fblogs%2Frunning%2Fcoaching-nutricional-moda-o-profesion%2F%23quote-1&amp;linkname=%E2%80%9CEl%20informar%20y%20dar%20consejo%20por%20parte%20del%20profesional%2C%26nbsp%3Bya%20no%20es%20suficiente%20para%20conseguir%20cambios%26nbsp%3Bde%20comportamiento%20a%20largo%20plazo%E2%80%9D.%26nbsp%3BOrganizaci%C3%B3n%20Mundial%20de%20la%20Salud%20%282003%29\" title=\"WhatsApp\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fblogs.forumsport.com%2Fes-es%2Fblogs%2Frunning%2Fcoaching-nutricional-moda-o-profesion%2F%23quote-1&amp;linkname=%E2%80%9CEl%20informar%20y%20dar%20consejo%20por%20parte%20del%20profesional%2C%26nbsp%3Bya%20no%20es%20suficiente%20para%20conseguir%20cambios%26nbsp%3Bde%20comportamiento%20a%20largo%20plazo%E2%80%9D.%26nbsp%3BOrganizaci%C3%B3n%20Mundial%20de%20la%20Salud%20%282003%29\" title=\"Email\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/div><\/div> <p>\u201cEl informar y dar consejo por parte del profesional,&nbsp;ya no es suficiente para conseguir cambios&nbsp;de comportamiento a largo plazo\u201d.&nbsp;Organizaci\u00f3n Mundial de la Salud (2003)<\/p><\/blockquote>\n<p>El <em>coach<\/em> nutricional gu\u00eda, ayuda, acompa\u00f1a y empodera a la persona a identificar sus objetivos<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5471\" data-permalink=\"\/es-es\/blogs\/running\/coaching-nutricional-moda-o-profesion\/coaching-1\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"coaching 1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1-1024x768.jpg\" class=\"aligncenter size-large wp-image-5471\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1-1024x768.jpg\" alt=\"coaching nutricional\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1.jpg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1-768x576.jpg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-1-800x600.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>\u00bfEn que puede ayudar el coaching nutricional al deportista?<\/h2>\n<p>Mejora la alimentaci\u00f3n y la adherencia a unos h\u00e1bitos de vida saludables, y por tanto optimiza la salud. En el deporte -donde la alimentaci\u00f3n juega un papel importante ya que tiene una relaci\u00f3n directa con la salud y rendimiento del deportista-, usamos el <em>coaching<\/em> para <strong>mejorar la adherencia a las pautas de nutrici\u00f3n deportiva y a un estilo de vida sana, obteniendo resultados ampliamente satisfactorios<\/strong>.<\/p>\n<h2>\u00bfQu\u00e9 diferencias hay entre el tratamiento tradicional y el tratamiento coaching nutricional?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5473\" data-permalink=\"\/es-es\/blogs\/running\/coaching-nutricional-moda-o-profesion\/tratamiento-tradicionalvscoaching\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"tratamiento tradicionalvscoaching\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching-1024x768.jpg\" class=\"aligncenter size-large wp-image-5473\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching-1024x768.jpg\" alt=\"coaching nutricional\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching.jpg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching-768x576.jpg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/tratamiento-tradicionalvscoaching-800x600.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>\u00bfEn qu\u00e9 ayuda el coaching nutricional?<\/h2>\n<ul>\n<li><strong>Ayuda a fijar metas y a definir objetivos nutricionales y\/o deportivos<\/strong>.&nbsp;El coach no decide, no impone, no &nbsp;dice lo que alguien debe hacer o no. Acompa\u00f1a y gu\u00eda a la persona a identificar su objetivo (u objetivos), y le ense\u00f1a a que est\u00e9 formulado en positivo, que sea medible, espec\u00edfico, asequible, retador y seguro.<\/li>\n<li>Al definir el objetivo en positivo, el paciente <strong>pone el foco del proceso y su empe\u00f1o en conseguir lo que quiere<\/strong>, en lugar de centrarse en el \u201cno puedo\u201d.<\/li>\n<li><strong>Identifica sus debilidades<\/strong> y los obst\u00e1culos que pueden aparecer a lo largo del proceso de cambio de h\u00e1bitos nutricionales. As\u00ed, si aparecen, tendr\u00e1 las herramientas para solucionarlos.<\/li>\n<li><strong>Empodera los puntos fuertes de la persona<\/strong> que est\u00e1 llevando a cabo este proceso de cambio y enumera los beneficios de conseguir las metas.<\/li>\n<li><strong>Fomenta el aprendizaje continuo<\/strong> y utiliza las habilidades y talentos del paciente.<\/li>\n<\/ul>\n<h2>C\u00f3mo comenzar un proceso de coaching nutricional<\/h2>\n<ul>\n<li><u><strong>Tomar conciencia<\/strong>:<\/u> identificar lo que quiero cambiar o mejorar, tener claros mis objetivos nutricionales y lo que es importante para m\u00ed.<\/li>\n<li><u><strong>Asumir la responsabilidad<\/strong>:<\/u> no hay nadie m\u00e1s responsable de lo que se consigue o no se consigue que uno mismo. El \u00e9xito depende de m\u00ed y yo soy el protagonista del cambio. Nadie puede conseguir por ti el cambio que deseas<\/li>\n<li><strong><u>Tener confianza<\/u><\/strong>: actuamos por lo que creemos que somos capaces de hacer,&nbsp; y no por lo que realmente somos capaces de hacer. El coaching nutricional nos ayuda a descubrir nuestras creencias y a mejorar nuestra actitud y aptitud para el cambio.<\/li>\n<li><strong><u>S\u00e9 proactivo y atr\u00e9vete a salir de tu zona de confort<\/u><\/strong>: si hay algo que no te gusta, pon el foco en buscar soluciones y c\u00e1mbialo.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5472\" data-permalink=\"\/es-es\/blogs\/running\/coaching-nutricional-moda-o-profesion\/exito\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito.jpg\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"exito\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito-1024x768.jpg\" class=\"aligncenter size-large wp-image-5472\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito-1024x768.jpg\" alt=\"coaching nutricional\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito.jpg 1024w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito-300x225.jpg 300w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito-768x576.jpg 768w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/exito-800x600.jpg 800w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>El coaching no es s\u00f3lo una t\u00e9cnica que hay que aplicar en determinadas circunstancias,&nbsp; es una filosof\u00eda de vida, un modo de relacionarse con las personas, una forma de pensar y una manera de ser: \u00bfQu\u00e9 te parece?<\/p>\n<p><em>Por <strong>Elena Jorr\u00edn&nbsp;<\/strong>(Dietista Nutricionista, especialista en nutrici\u00f3n deportiva y coach nutricional).<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace ya unos a\u00f1os que el t\u00e9rmino coaching y coach nos resulta familiar, pero \u00bfsabes realmente qu\u00e9 es el coaching? \u00bfEs tan solo una moda? \u00bfPor qu\u00e9 genera tanta confusi\u00f3n? Como dietista nutricionista y especialista en coaching nutricional, es hora de explicaros desde mis conocimientos y experiencia esta nueva disciplina. [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/coaching-nutricional-moda-o-profesion\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":5475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[5],"tags":[537,535,536],"class_list":{"0":"post-5470","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nutricion-y-salud","8":"tag-coach-nutricional","9":"tag-coaching","10":"tag-coaching-deportivo"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2017\/11\/coaching-nutricinal.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-1qe","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/5470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=5470"}],"version-history":[{"count":5,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/5470\/revisions"}],"predecessor-version":[{"id":5533,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/5470\/revisions\/5533"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/5475"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=5470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=5470"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=5470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}