{"id":9133,"date":"2019-06-18T11:41:15","date_gmt":"2019-06-18T09:41:15","guid":{"rendered":"\/es-es\/blogs\/running\/?p=9133"},"modified":"2024-06-19T12:46:05","modified_gmt":"2024-06-19T10:46:05","slug":"manias-de-los-runners-que-dan-asco-o-no","status":"publish","type":"post","link":"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/","title":{"rendered":"Man\u00edas de los runners que dan asco (o no)"},"content":{"rendered":"<p>\u00bf Man\u00edas de los runners ? Si los runners no tenemos man\u00edas\u2026y menos que den asco\u2026 No cuela \u00bfverdad? Por eso hemos querido hacer un post divertido pidi\u00e9ndoles a nuestr@s bloguer@s que nos cuenten h\u00e1bitos o momentos desagradables que han presenciado en carrera\u2026 Si sigues leyendo, lo que encontrar\u00e1s no va a ser bonito&#8230; \u00a1Pero s\u00ed divertido! \ud83d\ude42<\/p>\n<p><!--more--><\/p>\n<p>Entre las man\u00edas de los runners, adem\u00e1s de estos &#8220;<strong>momentos desagradables&#8221; de otros corredores<\/strong> \u2013porque ellas\/os no son as\u00ed, of course- <strong>que han presenciado durante su multitud de carreras y entrenamientos, <\/strong>hemos incluido tambi\u00e9n&nbsp;<strong>supersticiones, man\u00edas, excentricidades<\/strong> propias que les funcionan para optimizar su rendimiento\u2026.<\/p>\n<p>\u2026o al menos eso es lo que creen\u2026<\/p>\n<p><strong>Ya te hemos dicho que, si contin\u00faas leyendo, lo que encontrar\u00e1s no va a ser bonito<\/strong>: pis, ortigas, mocos, escupitajos\u2026pero seguro que te echas unas risas\u2026y a lo mejor en los comentarios podr\u00edas contarnos alguna experiencia similar que hayas vivido en tu trayectoria como corredor. Alguna cochinada que hayas visto en otros.<\/p>\n<p>Porque t\u00fa no eres as\u00ed, of course\u2026 \ud83d\ude09<\/p>\n<p><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"https:\/\/giphy.com\/embed\/z5WtAAaFpnIgU\" width=\"640\" height=\"427\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h2><strong>Roberto Garay: Mira lo que entiende \u00e9l por &#8220;PICARSE en carrera&#8221;<\/strong><\/h2>\n<p>Aunque ya son unos cuantos a\u00f1os los que llevo en el mundo del running -y m\u00e1s concretamente en el trail running-, no me considero un corredor mani\u00e1tico y las t\u00edpicas man\u00edas de los runners me son ajenas; soy de los que les gusta mantener la rutina diaria aunque s\u00ed que debo de reconocer que, dependiendo la distancia de la carrera y el nivel de cansancio que lleve, <strong>uso un truco infalible<\/strong>.<\/p>\n<p>Fue por pura casualidad en un ultra que se celebra en el Pa\u00eds Vasco cuando me di cuenta de que lo que en un primer momento hab\u00eda sido un \u201caccidente\u201d se convertir\u00eda en una <strong>t\u00e9cnica de resucitaci\u00f3n<\/strong> -en la ultradistancia se muere y se revive varias veces- <strong>m\u00e1s practica<\/strong> y eficaz <strong>que cualquier gel cargado de cafe\u00edna<\/strong>.<\/p>\n<p>Me refiero a la acci\u00f3n de <strong>ortigarme <\/strong>siendo consciente de ello; s\u00ed, s\u00ed, ortigarme <strong>voluntariamente<\/strong> en esos momentos en los que vas derrotado y por tu cabeza solo circula la idea de abandonar. Me sucedi\u00f3 en aquella carrera de forma fortuita despu\u00e9s de un traspi\u00e9s y <strong>desde entonces han sido varias carreras en las que me he ortigado voluntariamente<\/strong>: el picor hace que despiertes de tu letargo runero y que te pongas las pilas hasta que el efecto empiece a remitir. Os invito a tod@s a que experiment\u00e9is con esta t\u00e9cnica buena, bonita y barata.<\/p>\n<figure id=\"attachment_9248\" aria-describedby=\"caption-attachment-9248\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9248\" data-permalink=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/manias_runners_6\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_6.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manias_runners_6\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_6-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_6.jpg\" class=\"wp-image-9248 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_6.jpg\" alt=\"Man\u00edas de los runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_6.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_6-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-9248\" class=\"wp-caption-text\">Roberto, buscando ortigas con las que &#8220;motivarse&#8221;&#8230;<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><strong>Igor Quijano: Ha visto cosas que no creer\u00edas<\/strong><\/h2>\n<p>Compartir momentos con otros runners suele ser generalmente un motivo de alegr\u00eda. Y digo que suele ser, porque <strong>a veces te encuentras con gente que es capaz de hacer cosas que le revolver\u00edan las tripas a cualquiera<\/strong>. Un ejemplo claro de man\u00edas de los runners son esas personas que, incapaces de llevar un cl\u00ednex en alguno de sus bolsillos \u2013donde, dicho sea de paso, s\u00ed que le entran cinco geles, unas sales y un m\u00f3vil con pantalla de 52\u201d-, decide que <strong>aspirar para adentro<\/strong> como si no hubiera ma\u00f1ana es una idea genial.<\/p>\n<p>El resultado final suele ser una hermosa melod\u00eda entre trompetera y gutural que termina con la <strong>expulsi\u00f3n de una flema<\/strong> que por su tama\u00f1o y textura entre gelatinosa y cremosa m\u00e1s bien podr\u00eda ser un flan. Que t\u00fa que lo oyes y lo ves de cerca mal, <strong>PERO EL DE ATR\u00c1S QUE NO SE LO ESPERA Y LO PISA PEOR!<\/strong> Suerte si no se va al suelo del patinazo y termina revolc\u00e1ndose sobre tan sabroso regalito.<\/p>\n<p>Igual habr\u00eda que proponer que en los <strong>avituallamientos<\/strong> hubiera tambi\u00e9n pa\u00f1uelos, o por lo menos <strong>una escupidera<\/strong> como en el antiguo oeste. Aunque no s\u00e9 qu\u00e9 ser\u00eda peor :-p<\/p>\n<p><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"https:\/\/giphy.com\/embed\/i4rR1cu5VJqvcWNmPk\" width=\"480\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2><strong>Marta Anto\u00f1ana: Una carrera fluida<\/strong><\/h2>\n<p>\u00bfA qui\u00e9n no le ha ca\u00eddo en alguna ocasi\u00f3n alguna gotita de un moco o escupe ajeno?&nbsp; No me considero una persona escrupulosa pero no soporto la man\u00eda que tienen algunos runners de <strong>expulsar sus fluidos corporales a varios cientos de kil\u00f3metros por hora<\/strong> como si estos tambi\u00e9n entraran en la competici\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"https:\/\/giphy.com\/embed\/fnvybjQpHoOVTd87JK\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p>A m\u00ed personalmente me pasa que al ponerme a correr tengo la sensaci\u00f3n de que aumenta la producci\u00f3n de saliva o mucosidad y&nbsp;tengo esa necesidad de expulsarlo para continuar mi carrera c\u00f3modamente. Independientemente de esto, nuestro deber es respetar a los colegas que llevamos alrededor y comprobar que no haya nadie o limpiarnos antes de que las bacterias salgan volando sin rumbo.&nbsp;<\/p>\n<p>Una de mis man\u00edas es <strong>llevar una mu\u00f1equera<\/strong> o en invierno con los mismos manguitos, que adem\u00e1s de abrigarme <strong>me sirven para retirar exceso de sudor de la frente o moqueo nasal<\/strong>.<\/p>\n<figure id=\"attachment_9141\" aria-describedby=\"caption-attachment-9141\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9141\" data-permalink=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/manias_runners_1\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1.jpg\" data-orig-size=\"640,649\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manias_runners_1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1-296x300.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1.jpg\" class=\"wp-image-9141 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1.jpg\" alt=\"Man\u00edas de los runners\" width=\"640\" height=\"649\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1-296x300.jpg 296w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_1-592x600.jpg 592w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-9141\" class=\"wp-caption-text\">Marta, equipada para quitarse el sudor \/ moqueo de modo elegante&#8230;<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><strong>Andrea Fern\u00e1ndez: Runners mocosos&#8230;pero unos caballeros<\/strong><\/h2>\n<p>Personalmente, las man\u00edas de los runners que no aguanto son las de quienes&nbsp;<strong>se suenan los mocos con la mano<\/strong>, \u00bftanto cuesta llevar un pa\u00f1uelo en el bolsillo del pantal\u00f3n? \ud83e\udd74\ud83e\udd74 ah!! Y no queda ah\u00ed la cosa, porque muchos de ellos despu\u00e9s, al cruzar la meta, <strong>\u00a1te dan la mano!!!! Jajajaja&nbsp;<\/strong><\/p>\n<p>Y como man\u00eda personal <strong>no puedo colocarme en la salida de una competici\u00f3n sin mi cinta blanca en el pelo. Compito con ella desde los 7 a\u00f1os<\/strong>. Es mi talism\u00e1n \ud83c\udf40<\/p>\n<figure id=\"attachment_9145\" aria-describedby=\"caption-attachment-9145\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9145\" data-permalink=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/manias_runners_2\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_2.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manias_runners_2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_2-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_2.jpg\" class=\"wp-image-9145 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_2.jpg\" alt=\"Man\u00edas de los runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_2.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_2-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-9145\" class=\"wp-caption-text\">En <strong>2003<\/strong>, en el Cross Internacional Punta Parayas<\/figcaption><\/figure>\n<figure id=\"attachment_9147\" aria-describedby=\"caption-attachment-9147\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9147\" data-permalink=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/manias_runners_3\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3.jpg\" data-orig-size=\"640,674\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manias_runners_3\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3-285x300.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3.jpg\" class=\"wp-image-9147 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3.jpg\" alt=\"Man\u00edas de los runners\" width=\"640\" height=\"674\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3-285x300.jpg 285w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_3-570x600.jpg 570w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-9147\" class=\"wp-caption-text\">Un a\u00f1o despu\u00e9s, de nuevo con mi cinta blanca, en el Trofeo Baamonde (en la pista de Los Corrales de Buelna).<\/figcaption><\/figure>\n<figure id=\"attachment_9148\" aria-describedby=\"caption-attachment-9148\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9148\" data-permalink=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/manias_runners_4\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_4.jpg\" data-orig-size=\"640,504\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manias_runners_4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_4-300x236.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_4.jpg\" class=\"wp-image-9148 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_4.jpg\" alt=\"Man\u00edas de los runners\" width=\"640\" height=\"504\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_4.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_4-300x236.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-9148\" class=\"wp-caption-text\">&#8230;y 15 a\u00f1os despu\u00e9s, aqu\u00ed sigo, con mi amuleto en la frente&#8230;<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><strong>Imanol Loizaga: \u00c9stos son mis dominios<\/strong><\/h2>\n<p>Todos nos ponemos nerviosos en los minutos previos a una carrera y, a pesar de pasar varias veces por el WC, nos quedamos con ganas de una \u00faltima para la <strong>\u201cmeadita del miedo\u201d<\/strong>.<\/p>\n<p>En una marat\u00f3n hace varios a\u00f1os, bien apretados unos contra otros en el caj\u00f3n de salida, a un corredor no le pareci\u00f3 bastante la mezcla de olores que soport\u00e1bamos a base de cremas, sudor, linimento (y a saber qu\u00e9 m\u00e1s) y, ni corto ni perezoso, haciendo gala de una falta de todo, desde verg\u00fcenza hasta capacidad de aguante de su vejiga, <strong>se puso a orinar consiguiendo hacer un hueco de un metro a la redonda en donde parec\u00eda imposible sacar un palmo de sitio.<\/strong><\/p>\n<p>Su cara de alivio era tan incuestionable como la de cabreo de los que est\u00e1bamos alrededor. <strong>Menos mal que son\u00f3 el pistoletazo de salida casi de inmediato\u2026<\/strong><\/p>\n<div style=\"width: 480px;\"><iframe loading=\"lazy\" src=\"https:\/\/giphy.com\/embed\/mt2OWKicYdCSk26OsL\/video\" width=\"480\" height=\"270\" frameborder=\"0\"><\/iframe><\/div>\n<h2><strong>Ritxar Fern\u00e1ndez: Man\u00edas de los runners mentirosillos&#8230;<\/strong><\/h2>\n<p>No puedo decir que me d\u00e9 asco, pero me llaman mucho la atenci\u00f3n lan man\u00edan de los runners y conocidos que saludas cuando llegas a una carrera, y un comentario general que se hace es <strong>\u201c\u00a1No s\u00e9 para qu\u00e9 he venido, no estoy entrenando nada, este \u00faltimo mes he corrido tres d\u00edas!\u201d <\/strong><\/p>\n<p>Ahora, en cuanto suena el disparo, piernas para qu\u00e9 os quiero, no les vuelves a ver hasta la meta.<\/p>\n<p>Contento con haber podido entrenar tres o cuatro d\u00edas esa semana (y a veces conseguir hacer buenas carreras), piensas que estos tipos a poco que entrenen pueden ser unos cracks.\ud83d\ude1c.&nbsp;<\/p>\n<p><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"https:\/\/giphy.com\/embed\/NxEsKrLJXPuwg\" width=\"640\" height=\"427\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h2><strong>Hanot Echevarria: Le da palo contarlo, pero all\u00e1 va<\/strong><\/h2>\n<p>Especialmente en el monte, ya sea en un entrenamiento o compitiendo, <strong>me paso el recorrido entero cogiendo palitos, pi\u00f1as, ramas&#8230; Las voy troceando a medida que pasan los kil\u00f3metros<\/strong>. Cuanta m\u00e1s seca y m\u00e1s f\u00e1cil sencillo resulte romperla mejor, mayor disfrute. Cuando acabo con uno, busco otro y as\u00ed durante todo el recorrido.<\/p>\n<p>Tiene sus riesgos, ya que <strong>no siempre atinas a coger una rama adecuada y no ser\u00e1 la primera vez que me llevo alguna zarza<\/strong>, o intento partir una rama mientras corro pero no se parte y me quedo enganchado \ud83d\ude09 Especialmente interesante para series o cuestas, coger un palo seco al inicio de la serie y tenerlo troceado antes de acabarla, doble trabajo&#8230;.<\/p>\n<figure id=\"attachment_9173\" aria-describedby=\"caption-attachment-9173\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9173\" data-permalink=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/manias_runners_5\/\" data-orig-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_5.jpg\" data-orig-size=\"640,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"manias_runners_5\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Hanot,&lt;\/p&gt;\n\" data-medium-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_5-300x225.jpg\" data-large-file=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_5.jpg\" class=\"wp-image-9173 size-full\" src=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_5.jpg\" alt=\"Man\u00edas de los runners\" width=\"640\" height=\"480\" srcset=\"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_5.jpg 640w, \/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_5-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-9173\" class=\"wp-caption-text\">Hanot, probando las Bushido 2. Cuando dice &#8220;palitos&#8221;, espero que no se refiera a esto&#8230;<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>\u00bfTe han gustado estas man\u00edas de los runners? \u00bfHan sido suficientemente asquerosas? \ud83d\ude42<\/p>\n<p><strong>\u00bfY t\u00fa? \u00bfTienes alguna man\u00eda inconfesable como runner que, por lo que sea, te apetecer\u00eda compartir con nosotros? \u00bfHas visto cosas sumamente desagradables entrenando o en carrera y no quieres ser el \/ la \u00fanic@ traumatizad@ con esa imagen?<\/strong> <strong>\u00a1Cu\u00e9ntanoslo en los comentarios!<\/strong><\/p>\n<p>\u00a1Nosotras\/os te entendemos! \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bf Man\u00edas de los runners ? Si los runners no tenemos man\u00edas\u2026y menos que den asco\u2026 No cuela \u00bfverdad? Por eso hemos querido hacer un post divertido pidi\u00e9ndoles a nuestr@s bloguer@s que nos cuenten h\u00e1bitos o momentos desagradables que han presenciado en carrera\u2026 Si sigues leyendo, lo que encontrar\u00e1s no va a ser bonito&#8230; \u00a1Pero [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"\/es-es\/blogs\/running\/manias-de-los-runners-que-dan-asco-o-no\/\">Conocer m\u00e1s<\/a><\/p>\n","protected":false},"author":607,"featured_media":9134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"3","_mi_skip_tracking":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":{"0":"post-9133","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entrenamiento"},"jetpack_publicize_connections":[],"acf":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"\/es-es\/blogs\/running\/wp-content\/uploads\/sites\/2\/2019\/06\/manias_runners_portada.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6LYZF-2nj","jetpack-related-posts":[],"_links":{"self":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/9133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/users\/607"}],"replies":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/comments?post=9133"}],"version-history":[{"count":33,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/9133\/revisions"}],"predecessor-version":[{"id":21666,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/posts\/9133\/revisions\/21666"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media\/9134"}],"wp:attachment":[{"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/media?parent=9133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/categories?post=9133"},{"taxonomy":"post_tag","embeddable":true,"href":"\/es-es\/blogs\/running\/wp-json\/wp\/v2\/tags?post=9133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}